{"id":1017,"date":"2016-03-21T22:10:02","date_gmt":"2016-03-21T22:10:02","guid":{"rendered":"https:\/\/www.semanasantavinaros.es\/ss\/?p=1017"},"modified":"2016-03-21T22:10:02","modified_gmt":"2016-03-21T22:10:02","slug":"domingo-de-ramos","status":"publish","type":"post","link":"https:\/\/www.semanasantavinaros.es\/ss\/domingo-de-ramos\/","title":{"rendered":"Domingo de Ramos"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A las11,30 horas de la ma\u00f1ana se celebraba en las dos parroquias de nuestra ciudad, la solemnidad del \u201cDomingo de Ramos\u201d. En la Parroquia de \u201cSanta Magdalena\u201d con su p\u00e1rroco Mossen Crist\u00f3bal Zurita, contaron como cada a\u00f1o, con la colaboraci\u00f3n de la cofrad\u00eda de la \u201cHermandad de Nazarenos de Nuestra Padre Jes\u00fas Cautivo y Ntra. Sra. de la Merced\u201d, y su \u201cBande de cornetas y tambores\u201d, as\u00ed como con la participaci\u00f3n de la \u201cprocesi\u00f3n de la borriquilla\u201d. <\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-1018\" src=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/944389_1687756804812927_4385494973196978703_n.jpg\" alt=\"944389_1687756804812927_4385494973196978703_n\" width=\"900\" height=\"499\" srcset=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/944389_1687756804812927_4385494973196978703_n.jpg 900w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/944389_1687756804812927_4385494973196978703_n-300x166.jpg 300w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/944389_1687756804812927_4385494973196978703_n-768x426.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>Fuente Vinar\u00f2s News<\/em><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/szIJ-6c5Nho\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Por la calle Dr. Flem\u00edng se traslad\u00f3 la procesi\u00f3n hasta la Plaza 1\u00ba de Mayo, en que en el lugar de costumbre se realiz\u00f3 la bendici\u00f3n de ramos, ante una multitudinaria participaci\u00f3n de ni\u00f1os\/as y por supuesto, acompa\u00f1ados por sus pap\u00e1s y familiares. Seguidamente y de regreso a la parroquia se dio inicio a la \u201cMisa de ramos\u201d. El la parroquia Arciprestal de La Asunci\u00f3n, se formaba la procesi\u00f3n en la Plaza Parroquial, presidida por mossen Emilio Vinaixa, al cual acompa\u00f1aba el presidente de la F.C.S.S. Salvador Oliver.<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/DrRvd9pjAAA\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Estuvo precedida por la colaboraci\u00f3n de la \u201cBanda de bombos y tambores\u201d de la cofrad\u00eda del \u201cCristo de la Paz\u201d. Recorriendo la calle mayor se llegaba a la p\u00e9rgola del paseo, donde en este lugar se realiz\u00f3 la \u201cbendici\u00f3n de ramos\u201d. Mosen Emilio nos coment\u00f3 que seg\u00fan dicen nuestros mayores, la \u201cpuerta Plateresca\u201d, solo se habr\u00eda una vez al a\u00f1o, concretamente para esta procesi\u00f3n, pues que la vuelta a la parroquia se har\u00eda por la C\/. del \u00c1ngel, Plaza San Valente y pasaje, hasta entrar por esta puerta y seguidamente se realizar\u00eda la \u201cmisa del domingo de ramos\u201d. Esta procesi\u00f3n y bendici\u00f3n, en un soleado domingo, fue tambi\u00e9n muy concurrida.<\/p>\n<p style=\"text-align: justify;\">\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/M6LTFf0ca6c\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">En la Parroquia Arciprestal de La Asunci\u00f3n, se realizaba la <strong>misa en memoria de todos los cofrades fallecidos<\/strong> de todas las cofrad\u00edas de nuestra Semana Santa. En esta misa que es la adelantada del \u201cDomingo de Ramos\u201d, ya se leen las lecturas en la cual la mas importante es la de la pasi\u00f3n de Jesucristo seg\u00fan San Lucas. En la homil\u00eda mossen Emilio Porcar, p\u00e1rroco de la misma, realizo una importante y comprometida homil\u00eda comentando las lecturas resonadas anteriormente. Si bien este fue uno de los momentos m\u00e1s importantes, la lectura y el comentario de la pasi\u00f3n, si acaso, el mas emotivo fue en el momento de la invocaci\u00f3n de los difuntos.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/q1c_H3SuQdY\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las11,30 horas de la ma\u00f1ana se celebraba en las dos parroquias de nuestra ciudad, la solemnidad del \u201cDomingo de Ramos\u201d. En la Parroquia de \u201cSanta Magdalena\u201d con su p\u00e1rroco Mossen Crist\u00f3bal Zurita, contaron como cada a\u00f1o, con la colaboraci\u00f3n de la cofrad\u00eda de la \u201cHermandad de Nazarenos de Nuestra Padre Jes\u00fas Cautivo y Ntra.&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/www.semanasantavinaros.es\/ss\/domingo-de-ramos\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":1018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1017"}],"collection":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/comments?post=1017"}],"version-history":[{"count":1,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1017\/revisions"}],"predecessor-version":[{"id":1019,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1017\/revisions\/1019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media\/1018"}],"wp:attachment":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media?parent=1017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/categories?post=1017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/tags?post=1017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}