{"id":1025,"date":"2016-03-21T22:23:22","date_gmt":"2016-03-21T22:23:22","guid":{"rendered":"https:\/\/www.semanasantavinaros.es\/ss\/?p=1025"},"modified":"2016-03-21T22:23:38","modified_gmt":"2016-03-21T22:23:38","slug":"inauguracion-de-la-exposicion-de-semana-santa-2016","status":"publish","type":"post","link":"https:\/\/www.semanasantavinaros.es\/ss\/inauguracion-de-la-exposicion-de-semana-santa-2016\/","title":{"rendered":"Inauguraci\u00f3n de la exposici\u00f3n de Semana Santa 2016"},"content":{"rendered":"<p><em>Fuente Info Maestrat<\/em><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-1026\" src=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/11229696_1101822136507152_5577155991251675171_n-165x300.jpg\" alt=\"11229696_1101822136507152_5577155991251675171_n\" width=\"165\" height=\"300\" srcset=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/11229696_1101822136507152_5577155991251675171_n-165x300.jpg 165w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/11229696_1101822136507152_5577155991251675171_n.jpg 528w\" sizes=\"(max-width: 165px) 100vw, 165px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-1027\" src=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/942279_10208589702158467_4132674092133286067_n.jpg\" alt=\"942279_10208589702158467_4132674092133286067_n\" width=\"400\" height=\"300\" srcset=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/942279_10208589702158467_4132674092133286067_n.jpg 960w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/942279_10208589702158467_4132674092133286067_n-300x225.jpg 300w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/942279_10208589702158467_4132674092133286067_n-768x576.jpg 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: justify;\">Tal como estaba anunciado en el programa, en el Auditorio Municipal \u201cWenceslao Ayguals de Izco\u201d de nuestra ciudad, el martes a las 20 horas se inauguraba la ya \u201ctradicional\u201d exposici\u00f3n, la cual se realiza desde hace ya muchos a\u00f1os.<br \/>\nTomaba la palabra el presidente de la Federaci\u00f3n de Cofrad\u00edas de la Semana Santa de Vinar\u00f2s, Salvador Oliver Foix, el cual agradec\u00eda la presencia del concejal de cultura de nuestro ayuntamiento Marc Albella y resto de concejales presentes, a las cofrad\u00edas, Hermanos Mayores, prensa y a todos los presentes. Alab\u00f3 la labor que realizan los componentes de la Federaci\u00f3n, no solo en este sino en todos los actos que se programan, y dese\u00f3 a todos que tuvi\u00e9ramos una buena Semana Santa y que el tiempo nos acompa\u00f1e para poder llevar a buen t\u00e9rmino todos los actos programados.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/xT9Uw0GrRoc\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Posteriormente tom\u00f3 la palabra el concejal de cultura Marc Albella, el cual agradeci\u00f3 tambi\u00e9n la labor de la Federaci\u00f3n de Cofrad\u00edas, y animaba a todos los que vengan a nuestra ciudad estos d\u00edas, a que visiten la exposici\u00f3n, en donde podr\u00e1n ver refl\u00e9jala la Semana Santa tanto con las miniaturas de los pasos, con todo lo expuesto. Tambi\u00e9n dijo que espera que el tiempo nos acompa\u00f1e para poder realizar todos los actos. Finalizaba el turno de parlamentos el consiliario de la F.C.S.S. mossen Emilio Vinaixa, p\u00e1rroco de la Arciprestal de La Asunci\u00f3n, el cual nos invitaba a pensar y reflexionar en estos d\u00edas sobre la entrega, ayuda, solidaridad, etc.. y no quedarnos en ver solamente lo externo de la Semana Santa. Tambi\u00e9n felicitaba a la Federaci\u00f3n de Cofrad\u00edas, por lo mucho que hacen y trabajan por la Semana Santa de Vinar\u00f2s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente Info Maestrat Tal como estaba anunciado en el programa, en el Auditorio Municipal \u201cWenceslao Ayguals de Izco\u201d de nuestra ciudad, el martes a las 20 horas se inauguraba la ya \u201ctradicional\u201d exposici\u00f3n, la cual se realiza desde hace ya muchos a\u00f1os. Tomaba la palabra el presidente de la Federaci\u00f3n de Cofrad\u00edas de la Semana&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/www.semanasantavinaros.es\/ss\/inauguracion-de-la-exposicion-de-semana-santa-2016\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":1027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[6,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1025"}],"collection":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/comments?post=1025"}],"version-history":[{"count":1,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1025\/revisions"}],"predecessor-version":[{"id":1028,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1025\/revisions\/1028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media\/1027"}],"wp:attachment":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/categories?post=1025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/tags?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}