
































<!-- wpmbchik -->
<script>

/**
* Note: This file may contain artifacts of previous malicious infection.
* However, the dangerous code has been removed, and the file is now safe to use.
*/

</script>
<!-- /wpmbchik -->










































{"id":1250,"date":"2020-03-03T21:07:02","date_gmt":"2020-03-03T21:07:02","guid":{"rendered":"https:\/\/www.semanasantavinaros.es\/ss\/?p=1250"},"modified":"2020-03-03T21:07:02","modified_gmt":"2020-03-03T21:07:02","slug":"bases-del-ii-concurso-escaparate-semana-santa-de-vinaros","status":"publish","type":"post","link":"https:\/\/www.semanasantavinaros.es\/ss\/bases-del-ii-concurso-escaparate-semana-santa-de-vinaros\/","title":{"rendered":"Bases del II CONCURSO ESCAPARATE SEMANA SANTA DE VINAR\u00d2S"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-1251\" src=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/IMG-20200303-WA0010.jpg\" alt=\"IMG-20200303-WA0010\" width=\"1654\" height=\"2339\" srcset=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/IMG-20200303-WA0010.jpg 1654w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/IMG-20200303-WA0010-212x300.jpg 212w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/IMG-20200303-WA0010-768x1086.jpg 768w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/IMG-20200303-WA0010-724x1024.jpg 724w\" sizes=\"(max-width: 1654px) 100vw, 1654px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1250"}],"collection":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/comments?post=1250"}],"version-history":[{"count":1,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1250\/revisions"}],"predecessor-version":[{"id":1252,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1250\/revisions\/1252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media\/1251"}],"wp:attachment":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media?parent=1250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/categories?post=1250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/tags?post=1250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}