{"id":1341,"date":"2023-02-01T18:51:11","date_gmt":"2023-02-01T18:51:11","guid":{"rendered":"https:\/\/www.semanasantavinaros.es\/ss\/?p=1341"},"modified":"2023-02-01T18:51:13","modified_gmt":"2023-02-01T18:51:13","slug":"presentacion-pregonero-y-cartelanunciador-de-la-semana-santa-de-vinaros-2023","status":"publish","type":"post","link":"https:\/\/www.semanasantavinaros.es\/ss\/presentacion-pregonero-y-cartelanunciador-de-la-semana-santa-de-vinaros-2023\/","title":{"rendered":"PRESENTACION PREGONERO Y CARTEL<br>ANUNCIADOR DE LA SEMANA SANTA DE VINAR\u00d2S 2023"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"731\" height=\"1024\" src=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/SS_2023-731x1024.jpeg\" alt=\"\" class=\"wp-image-1342\" srcset=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/SS_2023-731x1024.jpeg 731w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/SS_2023-214x300.jpeg 214w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/SS_2023-768x1076.jpeg 768w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/SS_2023-1096x1536.jpeg 1096w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/SS_2023.jpeg 1142w\" sizes=\"(max-width: 731px) 100vw, 731px\" \/><\/figure>\n\n\n\n<p>El d\u00eda 31 de Enero de 2023, ha tenido lugar en el sal\u00f3n g\u00f3tico de la Iglesia Arciprestal, la rueda de prensa en la que la Federaci\u00f3n de Cofrad\u00edas de la Semana Santa de Vinar\u00f2s ha dado a conocer dos temas destacados de la presente edici\u00f3n.<\/p>\n\n\n\n<p>En primer lugar, Sebasti\u00e1n Torres Cam\u00f3s, presidente actual de la Federaci\u00f3n de Cofrad\u00edas de nuestra ciudad, ha anunciado que la pregonera ser\u00e1 Amparo Salvador M\u00ednguez. Actualmente es la presidenta de C\u00e1ritas de Vinar\u00f2s y es una vinarossenca muy querida en nuestra ciudad y que se hace querer en todos los \u00e1mbitos por los que transcurre su vida tanto a nivel laboral como personal.<br>Amparo es una persona de profundas ra\u00edces cristianas y muy comprometida en la vida parroquial de la Iglesia de Vinar\u00f2s.<\/p>\n\n\n\n<p>A continuaci\u00f3n la secretaria de la Federaci\u00f3n ha explicado las bases de la presente convocatoria del concurso de carteles de la Semana Santa de Vinar\u00f2s, declarada \u201cFesta d\u2019Inter\u00e9s Tur\u00edstic Auton\u00f2mic\u201d.<\/p>\n\n\n\n<p>En una primera fase, el pasado 23 de enero, de un total de 42 obras presentadas, de autores de procedencia tan diversa como Vinar\u00f2s, Murcia, Sevilla, Madrid, Jerez de la Frontera, X\u00e0tiva, Astorga, Lleida, Villena, Burriana, M\u00e1laga, Colombia y Argentina, entre otras, un jurado formado por 2 profesionales de la fotograf\u00eda y del dise\u00f1o gr\u00e1fico, el Concejal de Cultura del Ayuntamiento de Vinar\u00f2s y la Comisi\u00f3n Permanente de la Federaci\u00f3n de Cofrad\u00edas preseleccionaron 3 obras finalistas que pasaron a la segunda fase, y en la que los Hermanos Mayores y representantes de las cofrad\u00edas miembros de la Federaci\u00f3n fueron los encargados de votar para elegir la obra ganadora.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"577\" src=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/Setmana-Santa-cartel-1-1024x577.jpg\" alt=\"\" class=\"wp-image-1343\" srcset=\"https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/Setmana-Santa-cartel-1-1024x577.jpg 1024w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/Setmana-Santa-cartel-1-300x169.jpg 300w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/Setmana-Santa-cartel-1-768x432.jpg 768w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/Setmana-Santa-cartel-1-1536x865.jpg 1536w, https:\/\/www.semanasantavinaros.es\/ss\/wp-content\/uploads\/Setmana-Santa-cartel-1-2048x1153.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Foto Vinar\u00f2s News<\/em><\/figcaption><\/figure>\n\n\n\n<p><br>A continuaci\u00f3n Sebasti\u00e1n Torres ha dado a conocer las obras finalistas:<br><strong>2\u00ba FINALISTA:<br><\/strong>Obra: Mosaic Sant<br><strong><em>De Sebasti\u00e1n Casanova F\u00e1brega, de Vinar\u00f2s<\/em><\/strong><br><strong>1\u00ba FINALISTA:<br><\/strong>Obra: Camino de Resurrecci\u00f3n<br><strong><em>De Luciano An\u00edbal Petrosini Cuesta, de Valencia<\/em><\/strong><\/p>\n\n\n\n<p><strong>GANADOR del CARTEL DE LA SETMANA SANTA 2023, y premio de 800 \u20ac a la obra:<br>Una fe inmensa como el mar<br>De Crist\u00f3bal Aguil\u00f3 Dominguez de Cartagena (Murcia).<\/strong><\/p>\n\n\n\n<p>Seguidamente, el conciliario de la Federaci\u00f3n, Mn. Emilio Vinaixa, ha remarcado el mensaje que expresa la obra ganadora destacando el valor de esperanza de la Resurrecci\u00f3n de Nuestro Se\u00f1or, tras la muerte en la cruz, trasladando dicho mensaje simb\u00f3lico a nuestras vidas y a nuestro d\u00eda a d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 31 de Enero de 2023, ha tenido lugar en el sal\u00f3n g\u00f3tico de la Iglesia Arciprestal, la rueda de prensa en la que la Federaci\u00f3n de Cofrad\u00edas de la Semana Santa de Vinar\u00f2s ha dado a conocer dos temas destacados de la presente edici\u00f3n. En primer lugar, Sebasti\u00e1n Torres Cam\u00f3s, presidente actual de&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/www.semanasantavinaros.es\/ss\/presentacion-pregonero-y-cartelanunciador-de-la-semana-santa-de-vinaros-2023\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":1342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1341"}],"collection":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/comments?post=1341"}],"version-history":[{"count":1,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1341\/revisions"}],"predecessor-version":[{"id":1344,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/posts\/1341\/revisions\/1344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media\/1342"}],"wp:attachment":[{"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/media?parent=1341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/categories?post=1341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.semanasantavinaros.es\/ss\/wp-json\/wp\/v2\/tags?post=1341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}